{"id":488711,"date":"2022-11-02T16:24:16","date_gmt":"2022-11-02T16:24:16","guid":{"rendered":"https:\/\/inspire.vaude.com\/?page_id=488711"},"modified":"2022-11-04T17:30:48","modified_gmt":"2022-11-04T17:30:48","slug":"highlight-w23-45087","status":"publish","type":"page","link":"https:\/\/inspire.vaude.com\/fr\/highlight-w23-45087\/","title":{"rendered":"45087 Men&rsquo;s Kuro Insulation Halfzip Tricot"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb saved_tabs=\u00a0\u00bball\u00a0\u00bb global_module=\u00a0\u00bb489034&Prime;][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/inspire.vaude.com\/fr\/highlights-automne-hiver-2023-24\/\u00a0\u00bb button_text=\u00a0\u00bbAll Highlights\u00a0\u00bb button_alignment=\u00a0\u00bbright\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_bg_color=\u00a0\u00bb#4d4139&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_color=\u00a0\u00bbRGBA(0,0,0,0)\u00a0\u00bb button_border_radius=\u00a0\u00bb3px\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||-30px|||\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][et_pb_row padding_mobile=\u00a0\u00bboff\u00a0\u00bb column_padding_mobile=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb3.25&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb min_height=\u00a0\u00bb134px\u00a0\u00bb custom_css_main_element=\u00a0\u00bb padding-bottom: 5px;\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb||2px|\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb1px|||||\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_margin=\u00a0\u00bb||41px|||\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Men&rsquo;s Kuro Insulation Halfzip Tricot<br \/><\/span><\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay:flex;||flex-wrap:wrap;\u00a0\u00bb custom_css_before_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/11\/W23_BS_AR_M01_1H_XL_2TEC_d_23.png\u00a0\u00bb alt=\u00a0\u00bbMen&rsquo;s Kuro Insulation Halfzip Tricot\u00a0\u00bb title_text=\u00a0\u00bbW23_BS_AR_M01_1H_XL_2TEC_d_23&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb180px\u00a0\u00bb min_height_tablet=\u00a0\u00bb60px\u00a0\u00bb min_height_phone=\u00a0\u00bb10px\u00a0\u00bb min_height_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb height=\u00a0\u00bb180px\u00a0\u00bb height_tablet=\u00a0\u00bb60px\u00a0\u00bb height_phone=\u00a0\u00bb10px\u00a0\u00bb height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb max_height=\u00a0\u00bb180px\u00a0\u00bb max_height_tablet=\u00a0\u00bb60px\u00a0\u00bb max_height_phone=\u00a0\u00bb10px\u00a0\u00bb max_height_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_css_before_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Construction hybride pour courses gravel \u00e9piques. Le maillot isolant pour les cyclistes qui n\u2019ont pas froid aux yeux.<\/span><span style=\"font-size: xx-large;\"><br \/><\/span><\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bbdisplay:flex;||flex-wrap:wrap;\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bbdisplay:flex;||flex-wrap:wrap;\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_before_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bborder:2;\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bborder:2;\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb180px\u00a0\u00bb min_height_tablet=\u00a0\u00bb60px\u00a0\u00bb min_height_phone=\u00a0\u00bb10px\u00a0\u00bb min_height_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb height=\u00a0\u00bb180px\u00a0\u00bb height_tablet=\u00a0\u00bb60px\u00a0\u00bb height_phone=\u00a0\u00bb10px\u00a0\u00bb height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb max_height=\u00a0\u00bb180px\u00a0\u00bb max_height_tablet=\u00a0\u00bb60px\u00a0\u00bb max_height_phone=\u00a0\u00bb10px\u00a0\u00bb max_height_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_margin=\u00a0\u00bb||4px|||\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bbLine-height: 1.5 !important;\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bbLine-height: 1.5 !important;\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Construction hybride en zones l\u00e9g\u00e8res, respirantes et rembourr\u00e9es.<\/span><\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_before_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bborder:1;\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bborder:1;\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/11\/W23_BS_AR_M01_1H_XL_2TEC_d_31.png\u00a0\u00bb alt=\u00a0\u00bbMen&rsquo;s Kuro Insulation Halfzip Tricot \u2013 Hybrid\u00a0\u00bb title_text=\u00a0\u00bbMen&rsquo;s Kuro Insulation Halfzip Tricot \u2013 Hybrid\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bborder:1;\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb650.7px\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb499.9px\u00a0\u00bb custom_padding=\u00a0\u00bb||7px|||\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bbdisplay:flex;||flex-wrap:wrap;\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/11\/W23_BS_AR_M01_1H_XL_2TEC_d_33.png\u00a0\u00bb alt=\u00a0\u00bbMen&rsquo;s Kuro Insulation Halfzip Tricot \u2013 R\u00fccken\u00a0\u00bb title_text=\u00a0\u00bbMen&rsquo;s Kuro Insulation Halfzip Tricot \u2013 R\u00fccken\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb180px\u00a0\u00bb min_height_tablet=\u00a0\u00bb60px\u00a0\u00bb min_height_phone=\u00a0\u00bb10px\u00a0\u00bb min_height_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb height=\u00a0\u00bb180px\u00a0\u00bb height_tablet=\u00a0\u00bb60px\u00a0\u00bb height_phone=\u00a0\u00bb10px\u00a0\u00bb height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb max_height=\u00a0\u00bb180px\u00a0\u00bb max_height_tablet=\u00a0\u00bb60px\u00a0\u00bb max_height_phone=\u00a0\u00bb10px\u00a0\u00bb max_height_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|700|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb45px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb min_height=\u00a0\u00bb101.8px\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bbLine-height: 1.5 !important;\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bbLine-height: 1.5 !important;\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Deux poches ouvertes au dos ainsi qu\u2019une poche zipp\u00e9e permettent de transporter un smartphone et une barre \u00e9nerg\u00e9tique.<\/span><\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||5px|||\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb568.7px\u00a0\u00bb custom_margin=\u00a0\u00bb||0px|||\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay:flex;||flex-wrap:wrap;\u00a0\u00bb custom_css_before_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_css_after_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bbdisplay:flex;||flex-wrap:wrap;\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_after=\u00a0\u00bborder:2;\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bborder:2;\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb180px\u00a0\u00bb min_height_tablet=\u00a0\u00bb60px\u00a0\u00bb min_height_phone=\u00a0\u00bb10px\u00a0\u00bb min_height_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb height=\u00a0\u00bb180px\u00a0\u00bb height_tablet=\u00a0\u00bb60px\u00a0\u00bb height_phone=\u00a0\u00bb10px\u00a0\u00bb height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb max_height=\u00a0\u00bb180px\u00a0\u00bb max_height_tablet=\u00a0\u00bb60px\u00a0\u00bb max_height_phone=\u00a0\u00bb10px\u00a0\u00bb max_height_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Avec une isolation l\u00e9g\u00e8re de 40\u00a0g et une doublure a\u00e9rienne en mesh, qui \u00e9pouse agr\u00e9ablement et l\u00e9g\u00e8rement la peau, et qui renforce la respirabilit\u00e9.<\/span><\/strong>\u00a0<\/h2>\n<h2><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bborder:1;\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/11\/W23_BS_AR_M01_1H_XL_2TEC_d_19.png\u00a0\u00bb alt=\u00a0\u00bbMen&rsquo;s Kuro Insulation Halfzip Tricot \u2013 Material\u00a0\u00bb title_text=\u00a0\u00bbMen&rsquo;s Kuro Insulation Halfzip Tricot \u2013 Material\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb570.3px\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|||\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/11\/W23_BS_AR_M01_1H_XL_2TEC_d_32.png\u00a0\u00bb alt=\u00a0\u00bbMen&rsquo;s Kuro Insulation Halfzip Tricot \u2013 Silikonband\u00a0\u00bb title_text=\u00a0\u00bbMen&rsquo;s Kuro Insulation Halfzip Tricot \u2013 Silikonband\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb180px\u00a0\u00bb min_height_tablet=\u00a0\u00bb60px\u00a0\u00bb min_height_phone=\u00a0\u00bb10px\u00a0\u00bb min_height_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb height=\u00a0\u00bb180px\u00a0\u00bb height_tablet=\u00a0\u00bb60px\u00a0\u00bb height_phone=\u00a0\u00bb10px\u00a0\u00bb height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb max_height=\u00a0\u00bb180px\u00a0\u00bb max_height_tablet=\u00a0\u00bb60px\u00a0\u00bb max_height_phone=\u00a0\u00bb10px\u00a0\u00bb max_height_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Un ruban en silicone gaufr\u00e9 emp\u00eache le glissement du maillot vers le haut.<\/span><\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb568.7px\u00a0\u00bb custom_margin=\u00a0\u00bb||0px|||\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay:flex;||flex-wrap:wrap;\u00a0\u00bb custom_css_before_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_css_after_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bbdisplay:flex;||flex-wrap:wrap;\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_after=\u00a0\u00bborder:2;\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bborder:2;\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb180px\u00a0\u00bb min_height_tablet=\u00a0\u00bb60px\u00a0\u00bb min_height_phone=\u00a0\u00bb10px\u00a0\u00bb min_height_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb height=\u00a0\u00bb180px\u00a0\u00bb height_tablet=\u00a0\u00bb60px\u00a0\u00bb height_phone=\u00a0\u00bb10px\u00a0\u00bb height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb max_height=\u00a0\u00bb180px\u00a0\u00bb max_height_tablet=\u00a0\u00bb60px\u00a0\u00bb max_height_phone=\u00a0\u00bb10px\u00a0\u00bb max_height_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Le zip bidirectionnel garantit une gestion optimale de la temp\u00e9rature et de l\u2019humidit\u00e9.<\/span><\/strong>\u00a0<\/h2>\n<h2><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bborder:1;\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/11\/W23_BS_AR_M01_1H_XL_2TEC_d_34.png\u00a0\u00bb alt=\u00a0\u00bbMen&rsquo;s Kuro Insulation Halfzip Tricot \u2013 Zipper\u00a0\u00bb title_text=\u00a0\u00bbMen&rsquo;s Kuro Insulation Halfzip Tricot \u2013 Zipper\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Fabrication climatiquement neutre et principalement en mat\u00e9riaux recycl\u00e9s.<\/span><\/strong><strong><\/strong><\/h2>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/10\/ig-ma_recycled_pet.png\u00a0\u00bb alt=\u00a0\u00bbRecycled PET\u00a0\u00bb title_text=\u00a0\u00bbig-ma_recycled_pet\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_video src=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=8aoG8UNSs8A&#038;list=PLbtaTQrJfLEi58O8YtAVtabN8BTrYrQw9&#038;index=22&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Men&rsquo;s Kuro Insulation Halfzip TricotConstruction hybride pour courses gravel \u00e9piques. Le maillot isolant pour les cyclistes qui n\u2019ont pas froid aux yeux.Construction hybride en zones l\u00e9g\u00e8res, respirantes et rembourr\u00e9es.Deux poches ouvertes au dos ainsi qu\u2019une poche zipp\u00e9e permettent de transporter un smartphone et une barre \u00e9nerg\u00e9tique.Avec une isolation l\u00e9g\u00e8re de 40\u00a0g et une doublure a\u00e9rienne [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"[et_pb_section fb_built=\"1\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_margin=\"||-30px|||\" custom_padding=\"||0px|||\"][et_pb_row padding_mobile=\"off\" column_padding_mobile=\"on\" _builder_version=\"3.25\" background_size=\"initial\" background_position=\"top_left\" background_repeat=\"repeat\" min_height=\"134px\" custom_css_main_element=\" padding-bottom: 5px;\"][et_pb_column type=\"4_4\" _builder_version=\"3.25\" custom_padding=\"||2px|\" custom_padding__hover=\"|||\"][et_pb_divider show_divider=\"off\" disabled_on=\"on|off|off\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_padding=\"1px|||||\"][\/et_pb_divider][et_pb_text _builder_version=\"4.9.4\" _module_preset=\"default\" header_line_height=\"1.5em\" custom_margin=\"||41px|||\"]<h1 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Men's Kuro Insulation Halfzip Tricot<br \/><\/span><\/strong><\/h1>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\"1_2,1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_css_main_element=\"display:flex;||flex-wrap:wrap;\" custom_css_before_last_edited=\"on|phone\"][et_pb_column type=\"1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_image src=\"https:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/11\/W23_BS_AR_M01_1H_XL_2TEC_d_23.png\" alt=\"Men's Kuro Insulation Halfzip Tricot\" title_text=\"W23_BS_AR_M01_1H_XL_2TEC_d_23\" _builder_version=\"4.9.4\" _module_preset=\"default\"][\/et_pb_image][\/et_pb_column][et_pb_column type=\"1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_divider show_divider=\"off\" _builder_version=\"4.9.4\" _module_preset=\"default\" min_height=\"180px\" min_height_tablet=\"60px\" min_height_phone=\"10px\" min_height_last_edited=\"on|desktop\" height=\"180px\" height_tablet=\"60px\" height_phone=\"10px\" height_last_edited=\"on|phone\" max_height=\"180px\" max_height_tablet=\"60px\" max_height_phone=\"10px\" max_height_last_edited=\"on|tablet\" custom_padding=\"||0px|||\"][\/et_pb_divider][et_pb_text _builder_version=\"4.9.4\" _module_preset=\"default\" header_2_line_height=\"1.5em\" custom_css_before_last_edited=\"on|desktop\"]<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Hybrid construction for fast paced gravel riding. A thermal shirt for cyclists who love the mud.<\/span><span style=\"font-size: xx-large;\"><br \/><\/span><\/strong><\/h2>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\"1_2,1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_padding=\"0px|||||\" custom_css_main_element_last_edited=\"on|tablet\" custom_css_main_element_phone=\"display:flex;||flex-wrap:wrap;\" custom_css_main_element_tablet=\"display:flex;||flex-wrap:wrap;\"][et_pb_column type=\"1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_css_before_last_edited=\"on|phone\" custom_css_main_element_last_edited=\"on|desktop\" custom_css_main_element_phone=\"order:2;\" custom_css_main_element_tablet=\"order:2;\"][et_pb_divider show_divider=\"off\" _builder_version=\"4.9.4\" _module_preset=\"default\" min_height=\"180px\" min_height_tablet=\"60px\" min_height_phone=\"10px\" min_height_last_edited=\"on|desktop\" height=\"180px\" height_tablet=\"60px\" height_phone=\"10px\" height_last_edited=\"on|phone\" max_height=\"180px\" max_height_tablet=\"60px\" max_height_phone=\"10px\" max_height_last_edited=\"on|tablet\" custom_padding=\"||0px|||\"][\/et_pb_divider][et_pb_text _builder_version=\"4.9.4\" _module_preset=\"default\" header_2_line_height=\"1.5em\" custom_margin=\"||4px|||\" custom_css_main_element_last_edited=\"on|phone\" custom_css_main_element_phone=\"Line-height: 1.5 !important;\" custom_css_main_element_tablet=\"Line-height: 1.5 !important;\"]<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Hybrid construction with lightweight, breathable and insulated zones.<\/span><\/strong><\/h2>[\/et_pb_text][\/et_pb_column][et_pb_column type=\"1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_css_before_last_edited=\"on|desktop\" custom_css_main_element_last_edited=\"on|tablet\" custom_css_main_element_phone=\"order:1;\" custom_css_main_element_tablet=\"order:1;\"][et_pb_image src=\"https:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/11\/W23_BS_AR_M01_1H_XL_2TEC_d_31.png\" alt=\"Men's Kuro Insulation Halfzip Tricot \u2013 Hybrid\" title_text=\"Men's Kuro Insulation Halfzip Tricot \u2013 Hybrid\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_css_main_element_last_edited=\"on|phone\" custom_css_main_element_phone=\"order:1;\"][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.9.4\" _module_preset=\"default\" min_height=\"650.7px\" custom_padding=\"||0px|||\"][et_pb_row column_structure=\"1_2,1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\" min_height=\"499.9px\" custom_padding=\"||7px|||\" custom_css_main_element_last_edited=\"on|phone\" custom_css_main_element_phone=\"display:flex;||flex-wrap:wrap;\"][et_pb_column type=\"1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_image src=\"https:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/11\/W23_BS_AR_M01_1H_XL_2TEC_d_33.png\" alt=\"Men's Kuro Insulation Halfzip Tricot \u2013 R\u00fccken\" title_text=\"Men's Kuro Insulation Halfzip Tricot \u2013 R\u00fccken\" _builder_version=\"4.9.4\" _module_preset=\"default\"][\/et_pb_image][\/et_pb_column][et_pb_column type=\"1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_divider show_divider=\"off\" _builder_version=\"4.9.4\" _module_preset=\"default\" min_height=\"180px\" min_height_tablet=\"60px\" min_height_phone=\"10px\" min_height_last_edited=\"on|desktop\" height=\"180px\" height_tablet=\"60px\" height_phone=\"10px\" height_last_edited=\"on|phone\" max_height=\"180px\" max_height_tablet=\"60px\" max_height_phone=\"10px\" max_height_last_edited=\"on|tablet\" custom_padding=\"||0px|||\"][\/et_pb_divider][et_pb_text _builder_version=\"4.9.4\" _module_preset=\"default\" text_font=\"|700|||||||\" text_font_size=\"45px\" header_2_line_height=\"1.5em\" text_orientation=\"center\" min_height=\"101.8px\" custom_css_main_element_last_edited=\"on|phone\" custom_css_main_element_phone=\"Line-height: 1.5 !important;\" custom_css_main_element_tablet=\"Line-height: 1.5 !important;\"]<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Two open pockets and one zip pocket at the back provide space for your phone and a power bar.<\/span><\/strong><\/h2>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\"off|on|on\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_padding=\"||5px|||\"][et_pb_column type=\"4_4\" _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_divider show_divider=\"off\" disabled_on=\"off|on|on\" _builder_version=\"4.9.4\" _module_preset=\"default\"][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.9.4\" _module_preset=\"default\" min_height=\"568.7px\" custom_margin=\"||0px|||\" custom_padding=\"||0px|||\"][et_pb_row column_structure=\"1_2,1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_padding=\"0px|||||\" custom_css_main_element=\"display:flex;||flex-wrap:wrap;\" custom_css_before_last_edited=\"on|phone\" custom_css_main_element_last_edited=\"on|tablet\" custom_css_after_last_edited=\"on|phone\" custom_css_main_element_tablet=\"display:flex;||flex-wrap:wrap;\"][et_pb_column type=\"1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_css_after=\"order:2;\" custom_css_main_element_last_edited=\"on|phone\" custom_css_main_element_phone=\"order:2;\"][et_pb_divider show_divider=\"off\" _builder_version=\"4.9.4\" _module_preset=\"default\" min_height=\"180px\" min_height_tablet=\"60px\" min_height_phone=\"10px\" min_height_last_edited=\"on|desktop\" height=\"180px\" height_tablet=\"60px\" height_phone=\"10px\" height_last_edited=\"on|phone\" max_height=\"180px\" max_height_tablet=\"60px\" max_height_phone=\"10px\" max_height_last_edited=\"on|tablet\" custom_padding=\"||0px|||\"][\/et_pb_divider][et_pb_text _builder_version=\"4.9.4\" _module_preset=\"default\" header_2_line_height=\"1.5em\"]<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">With lightweight 40 g insulation and an airy mesh lining that supports breathability and is comfortable against your skin.<\/span><\/strong>\u00a0<\/h2>\r\n<h2><\/h2>[\/et_pb_text][\/et_pb_column][et_pb_column type=\"1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_css_main_element_last_edited=\"on|phone\" custom_css_main_element_phone=\"order:1;\"][et_pb_image src=\"https:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/11\/W23_BS_AR_M01_1H_XL_2TEC_d_19.png\" alt=\"Men's Kuro Insulation Halfzip Tricot \u2013 Material\" title_text=\"Men's Kuro Insulation Halfzip Tricot \u2013 Material\" _builder_version=\"4.9.4\" _module_preset=\"default\"][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.9.4\" _module_preset=\"default\" min_height=\"570.3px\" custom_padding=\"0px||0px|||\"][et_pb_row column_structure=\"1_2,1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_column type=\"1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_image src=\"https:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/11\/W23_BS_AR_M01_1H_XL_2TEC_d_32.png\" alt=\"Men's Kuro Insulation Halfzip Tricot \u2013 Silikonband\" title_text=\"Men's Kuro Insulation Halfzip Tricot \u2013 Silikonband\" _builder_version=\"4.9.4\" _module_preset=\"default\"][\/et_pb_image][\/et_pb_column][et_pb_column type=\"1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_divider show_divider=\"off\" _builder_version=\"4.9.4\" _module_preset=\"default\" min_height=\"180px\" min_height_tablet=\"60px\" min_height_phone=\"10px\" min_height_last_edited=\"on|desktop\" height=\"180px\" height_tablet=\"60px\" height_phone=\"10px\" height_last_edited=\"on|phone\" max_height=\"180px\" max_height_tablet=\"60px\" max_height_phone=\"10px\" max_height_last_edited=\"on|tablet\" custom_padding=\"||0px|||\"][\/et_pb_divider][et_pb_text _builder_version=\"4.9.4\" _module_preset=\"default\" header_2_line_height=\"1.5em\" custom_css_main_element_last_edited=\"on|phone\"]<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Textured silicone band prevents the jersey from sliding up.<\/span><\/strong><\/h2>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.9.4\" _module_preset=\"default\" min_height=\"568.7px\" custom_margin=\"||0px|||\" custom_padding=\"||0px|||\"][et_pb_row column_structure=\"1_2,1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_padding=\"0px|||||\" custom_css_main_element=\"display:flex;||flex-wrap:wrap;\" custom_css_before_last_edited=\"on|phone\" custom_css_main_element_last_edited=\"on|tablet\" custom_css_after_last_edited=\"on|phone\" custom_css_main_element_tablet=\"display:flex;||flex-wrap:wrap;\"][et_pb_column type=\"1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_css_after=\"order:2;\" custom_css_main_element_last_edited=\"on|phone\" custom_css_main_element_phone=\"order:2;\"][et_pb_divider show_divider=\"off\" _builder_version=\"4.9.4\" _module_preset=\"default\" min_height=\"180px\" min_height_tablet=\"60px\" min_height_phone=\"10px\" min_height_last_edited=\"on|desktop\" height=\"180px\" height_tablet=\"60px\" height_phone=\"10px\" height_last_edited=\"on|phone\" max_height=\"180px\" max_height_tablet=\"60px\" max_height_phone=\"10px\" max_height_last_edited=\"on|tablet\" custom_padding=\"||0px|||\"][\/et_pb_divider][et_pb_text _builder_version=\"4.9.4\" _module_preset=\"default\" header_2_line_height=\"1.5em\"]<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">The two-way front zip ensures optimal temperature and moisture management.<\/span><\/strong>\u00a0<\/h2>\r\n<h2><\/h2>[\/et_pb_text][\/et_pb_column][et_pb_column type=\"1_2\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_css_main_element_last_edited=\"on|phone\" custom_css_main_element_phone=\"order:1;\"][et_pb_image src=\"https:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/11\/W23_BS_AR_M01_1H_XL_2TEC_d_34.png\" alt=\"Men's Kuro Insulation Halfzip Tricot \u2013 Zipper\" title_text=\"Men's Kuro Insulation Halfzip Tricot \u2013 Zipper\" _builder_version=\"4.9.4\" _module_preset=\"default\"][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.9.4\" _module_preset=\"default\" custom_padding=\"||0px|||\"][et_pb_row _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_column type=\"4_4\" _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_text _builder_version=\"4.9.4\" _module_preset=\"default\" header_2_line_height=\"1.5em\" custom_padding=\"||0px|||\"]<h2 style=\"text-align: center;\"><strong><span style=\"font-size: xx-large;\">Offset for climate neutrality; primarily made from recycled materials.<\/span><\/strong><strong><\/strong><\/h2>[\/et_pb_text][et_pb_image src=\"https:\/\/inspire.vaude.com\/wp-content\/uploads\/2022\/10\/ig-ma_recycled_pet.png\" alt=\"Recycled PET\" title_text=\"ig-ma_recycled_pet\" _builder_version=\"4.9.4\" _module_preset=\"default\"][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\"4.9.4\" _module_preset=\"default\" custom_padding=\"||0px|||\"][et_pb_column type=\"4_4\" _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_divider show_divider=\"off\" _builder_version=\"4.9.4\" _module_preset=\"default\"][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_row _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_column type=\"4_4\" _builder_version=\"4.9.4\" _module_preset=\"default\"][et_pb_video src=\"https:\/\/www.youtube.com\/watch?v=8aoG8UNSs8A&list=PLbtaTQrJfLEi58O8YtAVtabN8BTrYrQw9&index=22\" _builder_version=\"4.9.4\" _module_preset=\"default\"][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]","_et_gb_content_width":"","footnotes":""},"class_list":["post-488711","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/inspire.vaude.com\/fr\/wp-json\/wp\/v2\/pages\/488711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inspire.vaude.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/inspire.vaude.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/inspire.vaude.com\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/inspire.vaude.com\/fr\/wp-json\/wp\/v2\/comments?post=488711"}],"version-history":[{"count":0,"href":"https:\/\/inspire.vaude.com\/fr\/wp-json\/wp\/v2\/pages\/488711\/revisions"}],"wp:attachment":[{"href":"https:\/\/inspire.vaude.com\/fr\/wp-json\/wp\/v2\/media?parent=488711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}